{"id":96,"count":1,"description":"","link":"https:\/\/woodshms.com\/wp\/tag\/pavement\/","name":"pavement","slug":"pavement","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>pavement Archives - Wood&#039;s Home Maintenance Service|Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/woodshms.com\/wp\/tag\/pavement\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/woodshms.com\\\/wp\\\/tag\\\/pavement\\\/\",\"url\":\"https:\\\/\\\/woodshms.com\\\/wp\\\/tag\\\/pavement\\\/\",\"name\":\"pavement Archives - Wood&#039;s Home Maintenance Service|Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/woodshms.com\\\/wp\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/woodshms.com\\\/wp\\\/tag\\\/pavement\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/woodshms.com\\\/wp\\\/tag\\\/pavement\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/woodshms.com\\\/wp\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"pavement\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/woodshms.com\\\/wp\\\/#website\",\"url\":\"https:\\\/\\\/woodshms.com\\\/wp\\\/\",\"name\":\"Wood&#039;s Home Maintenance Service|Blog\",\"description\":\"Tips, Advice  &amp; Discussions about the upkeep of your home!\",\"publisher\":{\"@id\":\"https:\\\/\\\/woodshms.com\\\/wp\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/woodshms.com\\\/wp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/woodshms.com\\\/wp\\\/#organization\",\"name\":\"Wood's Home Maintenance Service\",\"url\":\"https:\\\/\\\/woodshms.com\\\/wp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/woodshms.com\\\/wp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/woodshms.com\\\/wp\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/Whms-facebook-logo-a-jpeg.jpg\",\"contentUrl\":\"https:\\\/\\\/woodshms.com\\\/wp\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/Whms-facebook-logo-a-jpeg.jpg\",\"width\":750,\"height\":750,\"caption\":\"Wood's Home Maintenance Service\"},\"image\":{\"@id\":\"https:\\\/\\\/woodshms.com\\\/wp\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WoodsHomeMaintenanceService?ref=hl\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/2676945\",\"https:\\\/\\\/www.pinterest.com\\\/whms\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCIesJlwO8_QlmsMPjO2v0pw\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"pavement Archives - Wood&#039;s Home Maintenance Service|Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/woodshms.com\/wp\/tag\/pavement\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/woodshms.com\/wp\/tag\/pavement\/","url":"https:\/\/woodshms.com\/wp\/tag\/pavement\/","name":"pavement Archives - Wood&#039;s Home Maintenance Service|Blog","isPartOf":{"@id":"https:\/\/woodshms.com\/wp\/#website"},"breadcrumb":{"@id":"https:\/\/woodshms.com\/wp\/tag\/pavement\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/woodshms.com\/wp\/tag\/pavement\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/woodshms.com\/wp\/"},{"@type":"ListItem","position":2,"name":"pavement"}]},{"@type":"WebSite","@id":"https:\/\/woodshms.com\/wp\/#website","url":"https:\/\/woodshms.com\/wp\/","name":"Wood&#039;s Home Maintenance Service|Blog","description":"Tips, Advice  &amp; Discussions about the upkeep of your home!","publisher":{"@id":"https:\/\/woodshms.com\/wp\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/woodshms.com\/wp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/woodshms.com\/wp\/#organization","name":"Wood's Home Maintenance Service","url":"https:\/\/woodshms.com\/wp\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/woodshms.com\/wp\/#\/schema\/logo\/image\/","url":"https:\/\/woodshms.com\/wp\/wp-content\/uploads\/2014\/09\/Whms-facebook-logo-a-jpeg.jpg","contentUrl":"https:\/\/woodshms.com\/wp\/wp-content\/uploads\/2014\/09\/Whms-facebook-logo-a-jpeg.jpg","width":750,"height":750,"caption":"Wood's Home Maintenance Service"},"image":{"@id":"https:\/\/woodshms.com\/wp\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WoodsHomeMaintenanceService?ref=hl","https:\/\/www.linkedin.com\/company\/2676945","https:\/\/www.pinterest.com\/whms\/","https:\/\/www.youtube.com\/channel\/UCIesJlwO8_QlmsMPjO2v0pw"]}]}},"_links":{"self":[{"href":"https:\/\/woodshms.com\/wp\/wp-json\/wp\/v2\/tags\/96","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/woodshms.com\/wp\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/woodshms.com\/wp\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/woodshms.com\/wp\/wp-json\/wp\/v2\/posts?tags=96"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}